{"id":179,"date":"2009-09-21T17:50:00","date_gmt":"2009-09-21T17:50:00","guid":{"rendered":"http:\/\/www.verobreger.com\/wordpress\/?p=179"},"modified":"2021-04-15T12:07:09","modified_gmt":"2021-04-15T10:07:09","slug":"20090921a-titre-provisoire","status":"publish","type":"post","link":"https:\/\/www.verobreger.com\/wordpress\/2009\/09\/21\/20090921a-titre-provisoire\/","title":{"rendered":"A titre Provisoire"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\"><a href=\"https:\/\/i0.wp.com\/www.verobreger.com\/dotclear\/public\/COUVERTURES\/couverture-atp.jpg\" rel=\"lightbox\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"glossy\" style=\"float: left; margin: 0 1em 1em 0;\" title=\"couverture-atp.jpg, sept. 2009\" src=\"https:\/\/i0.wp.com\/www.verobreger.com\/dotclear\/public\/COUVERTURES\/couverture-atp.jpg?w=1505\" alt=\"\"><\/a>A Titre Provisoire<\/h1>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/i0.wp.com\/www.verobreger.com\/wordpress\/wp-content\/uploads\/2021\/04\/4-A-titre-provisoire2x.png\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2102\" data-permalink=\"https:\/\/www.verobreger.com\/wordpress\/4-a-titre-provisoire2x\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.verobreger.com\/wordpress\/wp-content\/uploads\/2021\/04\/4-A-titre-provisoire2x.png?fit=738%2C1152&amp;ssl=1\" data-orig-size=\"738,1152\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"4 &amp;#8211; A titre provisoire2x\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.verobreger.com\/wordpress\/wp-content\/uploads\/2021\/04\/4-A-titre-provisoire2x.png?fit=700%2C1093&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.verobreger.com\/wordpress\/wp-content\/uploads\/2021\/04\/4-A-titre-provisoire2x-700x1093.png?resize=350%2C547\" alt=\"\" class=\"wp-image-2102\" width=\"350\" height=\"547\" srcset=\"https:\/\/i0.wp.com\/www.verobreger.com\/wordpress\/wp-content\/uploads\/2021\/04\/4-A-titre-provisoire2x.png?resize=700%2C1093&amp;ssl=1 700w, https:\/\/i0.wp.com\/www.verobreger.com\/wordpress\/wp-content\/uploads\/2021\/04\/4-A-titre-provisoire2x.png?resize=192%2C300&amp;ssl=1 192w, https:\/\/i0.wp.com\/www.verobreger.com\/wordpress\/wp-content\/uploads\/2021\/04\/4-A-titre-provisoire2x.png?resize=173%2C270&amp;ssl=1 173w, https:\/\/i0.wp.com\/www.verobreger.com\/wordpress\/wp-content\/uploads\/2021\/04\/4-A-titre-provisoire2x.png?w=738&amp;ssl=1 738w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>A peine Gabrielle a-t-elle d\u00e9couvert son appartement sens dessus dessous que l\u2019on sonne \u00e0 sa porte.<br>La police vient l\u2019interroger \u00e0 propos de sa compagne : rapidement la disparition de Fanny ne fait aucun doute.<br>Tandis que Gabrielle va se plonger dans leur histoire pour tenter de comprendre ce qui se passe, le capitaine Marie-Jeanne Paradis va devoir d\u00e9m\u00ealer des liens obscurs et inavouables, pour retrouver la jeune photographe.<br>La vie des deux femmes pourra alors reprendre son cours, m\u00eame si la v\u00e9rit\u00e9 les aura \u00e0 jamais transform\u00e9es.<\/p><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">Mot de l\u2019\u00e9diteur<\/h3>\n\n\n\n<p>V\u00e9ronique Br\u00e9ger a choisi le suspense pour son 4e roman qui, au d\u00e9tour d\u2019une intrigue habilement men\u00e9e, nous entra\u00eene dans les m\u00e9andres de l\u2019histoire r\u00e9cente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Il \u00e9tait une fois\u2026 A titre provisoire<\/h3>\n\n\n\n<p>1ers mots : avril 2005<\/p>\n\n\n\n<p>Version initiales achev\u00e9e : mars 2006<\/p>\n\n\n\n<p>Ce roman est n\u00e9 d\u2019une rencontre. Une histoire dans l\u2019histoire. <br>La version initiale de En souvenir de demain \u00e9tait \u00e0 la relecture, j\u2019avais plusieurs projets en t\u00eate et je ne parvenais pas \u00e0 me d\u00e9cider. <br>J\u2019ai demand\u00e9 \u00e0 mon \u00e9ditrice une id\u00e9e, elle m\u2019a propos\u00e9 la \u00ab disparition \u00bb comme point de d\u00e9part. L\u2019une des h\u00e9ro\u00efnes devait rentrer chez elle et s\u2019apercevoir que sa copine avait disparu. <br>A l\u2019\u00e9poque, je participai \u00e0 un atelier d\u2019\u00e9criture. C\u2019est dans ce cadre que j\u2019ai rencontr\u00e9 Anne. L\u2019un des chantiers d\u2019\u00e9criture propos\u00e9 par l\u2019animatrice nous a permis de travailler ensemble. Cette 1\u00e8re collaboration m\u2019en a sugg\u00e9r\u00e9 une autre\u2026 et je n\u2019ai pas tard\u00e9 \u00e0 partager l&rsquo;hypoth\u00e8se\u2026<br>Outre sa personnalit\u00e9 et sa sensibilit\u00e9, Anne dispose d\u2019un atout que je souhaitai mettre \u00e0 contribution : son m\u00e9tier.<br>Depuis longtemps je souhaitais \u00e9crire une histoire avec un personnage de psychanalyste.<\/p>\n\n\n\n<p>Nous nous sommes retrouv\u00e9es un matin de printemps 2005 \u00e0 la table d\u2019un caf\u00e9 du 6\u00e8me arrondissement de Paris\u2026 A proximit\u00e9 de la rue o\u00f9 nous avons d\u00e9cid\u00e9 que deux des h\u00e9ro\u00efnes, Gabrielle Pascal et Fanny Perpitch, habiteraient.<br>Le point de d\u00e9part ayant \u00e9t\u00e9 fix\u00e9, il fallait une trame\u2026 causes, cons\u00e9quences, une \u00e9bauche de ce que serait l\u2019histoire\u2026 Nous avons b\u00e2ti le projet entre brioches, croissants et caf\u00e9s.<br>J\u2019ai laiss\u00e9 le soin \u00e0 Anne de cr\u00e9er le personnage de la psychanalyste\u2026 de lui donner nom, pr\u00e9nom, chair et \u00e2me\u2026<br>J\u2019ai pris en main Gabrielle et Fanny\u2026 <br>Pour que le suspense donne toute son ampleur il manquait un protagoniste. Au d\u00e9part c\u2019\u00e9tait un homme, mais rapidement le capitaine de police s\u2019est f\u00e9minis\u00e9.<\/p>\n\n\n\n<p>Au fil de nos \u00e9changes, nous nous sommes rendues compte que le travail \u00ab \u00e0 4 mains \u00bb ne pourrait pas se concr\u00e9tiser comme imagin\u00e9 au d\u00e9part. Nous avons donc pris une nouvelle option afin de ne pas bloquer le projet. Anne m\u2019a confi\u00e9 sa psy et elle a suivi l\u2019avancement du chantier en intervenant sur les sc\u00e8nes de psychanalyses.<\/p>\n\n\n\n<p>A titre provisoire est un suspense qui m\u00eale le destin de&nbsp;quatre femmes. La qu\u00eate en est le sujet principal. Qu\u00eate de soi, qu\u00eate de l\u2019autre, qu\u00eate d\u2019identit\u00e9\u2026<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Les musiques du livre<\/h3>\n\n\n\n<p>Pendant l\u2019\u00e9criture d\u2019A titre provisoire j\u2019ai \u00e9cout\u00e9\u2026<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Gabrielle : Rise \/ Picking up the pieces \/ Play to win<\/li><li>The Organ : Grab That Gun<\/li><li>Sarah Bettens : Scream<\/li><li>Alanis Morissette : The Collection<\/li><li>Indochine : Alice et June<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"http:\/\/www.ktmeditions.com\/roman-lesbien\/6-a-titre-provisoire.html\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2147\" data-permalink=\"https:\/\/www.verobreger.com\/wordpress\/2009\/10\/01\/20091001la-nuit-des-orpailleurs\/buy\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.verobreger.com\/wordpress\/wp-content\/uploads\/2009\/10\/buy.png?fit=128%2C128&amp;ssl=1\" data-orig-size=\"128,128\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"buy\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.verobreger.com\/wordpress\/wp-content\/uploads\/2009\/10\/buy.png?fit=128%2C128&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/www.verobreger.com\/wordpress\/wp-content\/uploads\/2009\/10\/buy.png?resize=32%2C32&#038;ssl=1\" alt=\"\" class=\"wp-image-2147\" width=\"32\" height=\"32\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"http:\/\/www.ktmeditions.com\/roman-lesbien\/6-a-titre-provisoire.html\" target=\"_blank\" rel=\"noreferrer noopener\">Commander<\/a><\/h3>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Titre Provisoire A peine Gabrielle a-t-elle d\u00e9couvert son appartement sens dessus dessous que l\u2019on sonne \u00e0 sa porte.La police vient l\u2019interroger \u00e0 propos de[\u2026]<\/p>\n","protected":false},"author":2,"featured_media":2102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-romans"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.verobreger.com\/wordpress\/wp-content\/uploads\/2021\/04\/4-A-titre-provisoire2x.png?fit=738%2C1152&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p4t416-2T","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.verobreger.com\/wordpress\/wp-json\/wp\/v2\/posts\/179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.verobreger.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.verobreger.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.verobreger.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.verobreger.com\/wordpress\/wp-json\/wp\/v2\/comments?post=179"}],"version-history":[{"count":5,"href":"https:\/\/www.verobreger.com\/wordpress\/wp-json\/wp\/v2\/posts\/179\/revisions"}],"predecessor-version":[{"id":2222,"href":"https:\/\/www.verobreger.com\/wordpress\/wp-json\/wp\/v2\/posts\/179\/revisions\/2222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.verobreger.com\/wordpress\/wp-json\/wp\/v2\/media\/2102"}],"wp:attachment":[{"href":"https:\/\/www.verobreger.com\/wordpress\/wp-json\/wp\/v2\/media?parent=179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.verobreger.com\/wordpress\/wp-json\/wp\/v2\/categories?post=179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.verobreger.com\/wordpress\/wp-json\/wp\/v2\/tags?post=179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}